{"id":580,"date":"2019-06-27T17:20:24","date_gmt":"2019-06-27T15:20:24","guid":{"rendered":"https:\/\/www.ilpoliedro.org\/site\/?p=580"},"modified":"2025-05-01T12:06:03","modified_gmt":"2025-05-01T10:06:03","slug":"polo-museale-garavelle","status":"publish","type":"post","link":"https:\/\/www.ilpoliedro.org\/site\/polo-museale-garavelle\/","title":{"rendered":"POLO MUSEALE GARAVELLE"},"content":{"rendered":"<h2><strong>Polo Museale Garavelle &#8211; Centro delle Tradizioni Popolari <\/strong><strong>e Museo malacologico Malakos<\/strong><\/h2>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-551 aligncenter\" src=\"https:\/\/www.ilpoliedro.org\/site\/wp-content\/uploads\/2019\/06\/garavelle-300x122.jpg\" alt=\"\" width=\"403\" height=\"164\" srcset=\"https:\/\/www.ilpoliedro.org\/site\/wp-content\/uploads\/2019\/06\/garavelle-300x122.jpg 300w, https:\/\/www.ilpoliedro.org\/site\/wp-content\/uploads\/2019\/06\/garavelle.jpg 350w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/strong><\/p>\n<p>Localit\u00e0 Garavelle<\/p>\n<p>06012 Citt\u00e0 di Castello (PG)<\/p>\n<p>Gestione Il Poliedro Soc.Coop.Soc. &#8211; Area Cultura<\/p>\n<p>tel. 335\/460050\u00a0\u00a0\u00a0 075\/8554202\u00a0\u00a0 075\/8520656\u00a0 075\/8552119\u00a0\u00a0 cultura@ilpoliedro.org<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Orari di Apertura<\/strong><\/p>\n<p><strong>Sabato, domenica, festivi e prefestivi; <\/strong><\/p>\n<p><strong>tutti gli altri giorni<\/strong> chiamando i numeri di riferimento apertura su chiamata con un attesa massima di 20 minuti.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Orario<\/strong><\/p>\n<p><strong>Invernale:<\/strong>\u00a0 <strong>1 Novembre-31 Marzo<\/strong><\/p>\n<p>mattina 10.00 -12.30\u00a0\u00a0 pomeriggio 14.30-18.00<\/p>\n<p>chiuso i luned\u00ec (ad eccezione dei festivi e prefestivi) il 25 dicembre e il 1 gennaio.<\/p>\n<p><strong>Estivo:<\/strong> <strong>1 aprile &#8211; 31 ottobre<\/strong><\/p>\n<p>mattina 10.00 -12.30\u00a0 pomeriggio 15.00-18.30<\/p>\n<p>chiuso il luned\u00ec (ad eccezione dei festivi e prefestivi)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prezzi <\/strong><\/p>\n<p>BIGLIETTO INTERO\u00a0\u00a0 \u20ac\u00a0 6.00<\/p>\n<p>BIGLIETTO RIDOTTO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u20ac\u00a0 4.00 Gruppi superiori alle 15 persone, Visitatori di et\u00e0 compresa tra i 6 e i 14 anni, Visitatori di et\u00e0 superiore ai 65 anni<\/p>\n<p>BIGLIETTO GRATUITO Visitatori di et\u00e0 inferiore a 6 anni, Scuole del Comune di Citt\u00e0 di Castello<\/p>\n<p><strong>Per prenotazioni visite guidate:<\/strong><\/p>\n<p><strong>Il Poliedro Soc.Coop.Soc. &#8211;\u00a0 Area Cultura<\/strong><\/p>\n<p><strong>tel. 075\/8520656\u00a0\u00a0 075\/8554202\u00a0\u00a0\u00a0\u00a0 <\/strong><a href=\"mailto:cultura@ilpoliedro.org\"><strong>cultura@ilpoliedro.org<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polo Museale Garavelle &#8211; Centro delle Tradizioni Popolari e Museo malacologico Malakos Localit\u00e0 Garavelle 06012 Citt\u00e0 di Castello (PG) Gestione Il Poliedro Soc.Coop.Soc. &#8211; Area Cultura tel. 335\/460050\u00a0\u00a0\u00a0 075\/8554202\u00a0\u00a0 075\/8520656\u00a0 075\/8552119\u00a0\u00a0 cultura@ilpoliedro.org \u00a0 Orari di Apertura Sabato, domenica, festivi e prefestivi; tutti gli altri giorni chiamando i numeri di riferimento apertura su chiamata con un [&hellip;]<\/p>\n","protected":false},"author":71,"featured_media":551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,21],"tags":[],"class_list":["post-580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-orari-musei"],"_links":{"self":[{"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/posts\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/comments?post=580"}],"version-history":[{"count":2,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/posts\/580\/revisions"}],"predecessor-version":[{"id":942,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/posts\/580\/revisions\/942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/media\/551"}],"wp:attachment":[{"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/media?parent=580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/categories?post=580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilpoliedro.org\/site\/wp-json\/wp\/v2\/tags?post=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}